{"id":400,"date":"2021-08-23T16:59:08","date_gmt":"2021-08-23T19:59:08","guid":{"rendered":"https:\/\/inchurch.com.br\/brain\/?p=400"},"modified":"2021-08-23T16:59:10","modified_gmt":"2021-08-23T19:59:10","slug":"abandono-pastoral-como-lidar-com-o-esgotamento","status":"publish","type":"post","link":"https:\/\/inchurch.com.br\/brain\/abandono-pastoral-como-lidar-com-o-esgotamento\/","title":{"rendered":"Abandono pastoral: como lidar com o esgotamento"},"content":{"rendered":"\n<p>Muitos pastores abandonaram o cargo por causa do esgotamento.<\/p>\n\n\n\n<p>Embora fa\u00e7amos a obra de Deus, temos que estar cientes da nossa humanidade.<\/p>\n\n\n\n<p>Ou seja, a vida do pastor deve ser equilibrada fisicamente e emocionalmente.<\/p>\n\n\n\n<p>Uma pesquisa da Universidade de Duke mostrou que os pastores s\u00e3o mais propensos a ficarem com depress\u00e3o e ansiedade.<\/p>\n\n\n\n<h2>Mas afinal, como acontece o esgotamento pastoral?<\/h2>\n\n\n\n<p>\u00c9 comum um pastor sentir a necessidade de atender a todos que precisam.<\/p>\n\n\n\n<p>No entanto, a rotina de trabalho pode minar todas as for\u00e7as e energia.<\/p>\n\n\n\n<p>Como consequ\u00eancia, a esposa e os filhos podem ficar sobrecarregados.<\/p>\n\n\n\n<p>O esgotamento, por sua vez, vem quando as prioridades est\u00e3o desalinhadas.<\/p>\n\n\n\n<p>Isto \u00e9, quando se envolve demais no minist\u00e9rio e acaba deixando a sa\u00fade de lado.<\/p>\n\n\n\n<p>Logo, se n\u00e3o existe um equil\u00edbrio entre a vida pessoal e profissional a conta pode chegar.<\/p>\n\n\n\n<p>O abandono pastoral acontece por causa de uma sobrecarga muito grande na obra.<\/p>\n\n\n\n<p>Visto que, os pastores de modo geral t\u00eam dificuldades de separar um tempo para cuidar de si.<\/p>\n\n\n\n<p>Outro fator que piorou a situa\u00e7\u00e3o nesses \u00faltimos anos, foi a pandemia.<\/p>\n\n\n\n<p>Pois, a crise da Covid-19 trouxe s\u00e9rias preocupa\u00e7\u00f5es para os pastores e seu minist\u00e9rio.<\/p>\n\n\n\n<h2>O que fazer para evitar o abandono do minist\u00e9rio pastoral?<\/h2>\n\n\n\n<p>Como j\u00e1 vimos, o abandono pastoral acontece por causa da sobrecarga de atividades.<\/p>\n\n\n\n<p>Muitos pastores acabam deixando suas fam\u00edlias e sua sa\u00fade em segundo plano.<\/p>\n\n\n\n<p>Para evitar que isso ocorra \u00e9 necess\u00e1rio tomar algumas medidas.<\/p>\n\n\n\n<p>Em primeiro lugar \u00e9 preciso cuidar da sa\u00fade mental e f\u00edsica.<\/p>\n\n\n\n<p>Assim, todo pastor deve ter um mentor, um outro pastor mais experiente.<\/p>\n\n\n\n<p>Poder contar com algu\u00e9m, sobretudo descarrega as frustra\u00e7\u00f5es.<\/p>\n\n\n\n<p>Al\u00e9m disso, ajuda a enxergar as coisas de outro modo e uma sa\u00edda no fim do t\u00fanel.<\/p>\n\n\n\n<p>Por outro lado, quando um pastor j\u00e1 est\u00e1 em crise, \u00e9 preciso procurar ajuda profissional.<\/p>\n\n\n\n<p>No entanto, a sa\u00fade mental \u00e9 muito importante para evitar problemas ps\u00edquicos.<\/p>\n\n\n\n<h3>Veja 10&nbsp; maneiras de cuidar da sa\u00fade mental e f\u00edsica:<\/h3>\n\n\n\n<ul><li>pratique atividade f\u00edsica;<\/li><li>fa\u00e7a medita\u00e7\u00e3o;<\/li><li>leitura da Palavra de Deus;<\/li><li>momentos de ora\u00e7\u00e3o;<\/li><li>lazer;<\/li><li>bom sono;<\/li><li>boa alimenta\u00e7\u00e3o;<\/li><li>tenha momentos descontra\u00eddos com a fam\u00edlia e amigos;<\/li><li>contemple a natureza de Deus;<\/li><li>tire um tempo para se conhecer.<\/li><\/ul>\n\n\n\n<h2>Como lidar com o esgotamento pastoral?<\/h2>\n\n\n\n<p>Para lidar com o esgotamento pastoral \u00e9 preciso ter um planejamento de rotina.<\/p>\n\n\n\n<p>Ou seja, organizar todas as suas tarefas de modo que n\u00e3o sobrecarregue.<\/p>\n\n\n\n<p>Separe todas as atividades importantes e urgentes.<\/p>\n\n\n\n<p>E em seguida, delegue as demais para os l\u00edderes da igreja.<\/p>\n\n\n\n<p>Dessa forma, voc\u00ea ter\u00e1 tempo para cuidar de si e da sua fam\u00edlia.<\/p>\n\n\n\n<p>Al\u00e9m disso, \u00e9 preciso se fortalecer espiritualmente.<\/p>\n\n\n\n<p>Acontece que o pastor alimenta muito a suas ovelhas, mas esquece de ser alimentado espiritualmente.<\/p>\n\n\n\n<p>Assim sendo, procure equilibrar todos os seus afazeres para n\u00e3o chegar ao ponto de abandonar o pastorado.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Pesquisa da Universidade de Duke mostrou que os pastores s\u00e3o mais propensos a ficarem com depress\u00e3o e ansiedade.<\/p>\n","protected":false},"author":14,"featured_media":402,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[8],"tags":[21],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v15.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Abandono pastoral: como lidar com o esgotamento<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/inchurch.com.br\/brain\/abandono-pastoral-como-lidar-com-o-esgotamento\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Abandono pastoral: como lidar com o esgotamento\" \/>\n<meta property=\"og:description\" content=\"Pesquisa da Universidade de Duke mostrou que os pastores s\u00e3o mais propensos a ficarem com depress\u00e3o e ansiedade.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/inchurch.com.br\/brain\/abandono-pastoral-como-lidar-com-o-esgotamento\/\" \/>\n<meta property=\"og:site_name\" content=\"BrainChurch\" \/>\n<meta property=\"article:published_time\" content=\"2021-08-23T19:59:08+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-08-23T19:59:10+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/inchurch.com.br\/brain\/wp-content\/uploads\/2021\/08\/Esgotamento-pastoral.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1500\" \/>\n\t<meta property=\"og:image:height\" content=\"1003\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\">\n\t<meta name=\"twitter:data1\" content=\"Michael Caceres\">\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\">\n\t<meta name=\"twitter:data2\" content=\"2 minutos\">\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebSite\",\"@id\":\"https:\/\/inchurch.com.br\/brain\/#website\",\"url\":\"https:\/\/inchurch.com.br\/brain\/\",\"name\":\"BrainChurch\",\"description\":\"Centro de Pesquisa e Inova\\u00e7\\u00e3o inChurch\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":\"https:\/\/inchurch.com.br\/brain\/?s={search_term_string}\",\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"ImageObject\",\"@id\":\"https:\/\/inchurch.com.br\/brain\/abandono-pastoral-como-lidar-com-o-esgotamento\/#primaryimage\",\"inLanguage\":\"pt-BR\",\"url\":\"https:\/\/inchurch.com.br\/brain\/wp-content\/uploads\/2021\/08\/Esgotamento-pastoral.jpg\",\"width\":1500,\"height\":1003,\"caption\":\"Esgotamento pastoral\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/inchurch.com.br\/brain\/abandono-pastoral-como-lidar-com-o-esgotamento\/#webpage\",\"url\":\"https:\/\/inchurch.com.br\/brain\/abandono-pastoral-como-lidar-com-o-esgotamento\/\",\"name\":\"Abandono pastoral: como lidar com o esgotamento\",\"isPartOf\":{\"@id\":\"https:\/\/inchurch.com.br\/brain\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/inchurch.com.br\/brain\/abandono-pastoral-como-lidar-com-o-esgotamento\/#primaryimage\"},\"datePublished\":\"2021-08-23T19:59:08+00:00\",\"dateModified\":\"2021-08-23T19:59:10+00:00\",\"author\":{\"@id\":\"https:\/\/inchurch.com.br\/brain\/#\/schema\/person\/5669958267e262ddb77591d778c63d21\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/inchurch.com.br\/brain\/abandono-pastoral-como-lidar-com-o-esgotamento\/\"]}]},{\"@type\":\"Person\",\"@id\":\"https:\/\/inchurch.com.br\/brain\/#\/schema\/person\/5669958267e262ddb77591d778c63d21\",\"name\":\"Michael Caceres\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\/\/inchurch.com.br\/brain\/#personlogo\",\"inLanguage\":\"pt-BR\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/b114e46811f8c1e5a7b544f0bb50a9b3?s=96&d=mm&r=g\",\"caption\":\"Michael Caceres\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","_links":{"self":[{"href":"https:\/\/inchurch.com.br\/brain\/wp-json\/wp\/v2\/posts\/400"}],"collection":[{"href":"https:\/\/inchurch.com.br\/brain\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/inchurch.com.br\/brain\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/inchurch.com.br\/brain\/wp-json\/wp\/v2\/users\/14"}],"replies":[{"embeddable":true,"href":"https:\/\/inchurch.com.br\/brain\/wp-json\/wp\/v2\/comments?post=400"}],"version-history":[{"count":2,"href":"https:\/\/inchurch.com.br\/brain\/wp-json\/wp\/v2\/posts\/400\/revisions"}],"predecessor-version":[{"id":404,"href":"https:\/\/inchurch.com.br\/brain\/wp-json\/wp\/v2\/posts\/400\/revisions\/404"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/inchurch.com.br\/brain\/wp-json\/wp\/v2\/media\/402"}],"wp:attachment":[{"href":"https:\/\/inchurch.com.br\/brain\/wp-json\/wp\/v2\/media?parent=400"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/inchurch.com.br\/brain\/wp-json\/wp\/v2\/categories?post=400"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/inchurch.com.br\/brain\/wp-json\/wp\/v2\/tags?post=400"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}